{"id":280,"date":"2019-01-16T12:44:02","date_gmt":"2019-01-16T12:44:02","guid":{"rendered":"https:\/\/cedessl.org\/web1\/?p=280"},"modified":"2019-01-16T12:44:02","modified_gmt":"2019-01-16T12:44:02","slug":"fuente-inagotable-de-energia-el-mar","status":"publish","type":"post","link":"https:\/\/cedessl.org\/web1\/2019\/01\/16\/fuente-inagotable-de-energia-el-mar\/","title":{"rendered":"Fuente inagotable de energ\u00eda: El Mar"},"content":{"rendered":"<h4>El aprovechamiento de mar para generar electricidad.<\/h4>\n<p>Los Mares y oc\u00e9anos poseen un enorme potencial energ\u00e9tico que, a trav\u00e9s del uso de diferentes tecnolog\u00edas, pueden transformar en electricidad y ayuda a satisfacer las necesidades energ\u00e9ticas.<\/p>\n<p>Se pueden clasificar las Energ\u00edas del Mar, en funci\u00f3n de tecnolog\u00edas del tipo de aprovechamiento energ\u00e9tico. Y por ello tenemos las distintas tipolog\u00edas de energ\u00edas del mar:<\/p>\n<h4>Tipolog\u00edas:<\/h4>\n<p>1.- Energ\u00eda de las corrientes: es el aprovechamiento de la energ\u00eda cin\u00e9tica de las corrientes marinas. El proceso de captaci\u00f3n est\u00e1 basado en convertir la energ\u00eda cin\u00e9tica a los aerogeneradores.<\/p>\n<p>2.- Energ\u00eda de las olas o Undimotriz: se trata del aprovechamiento energ\u00e9tico producido por el movimiento ondulatorio de la superficie del agua del mar. Se han desarrollado m\u00faltiples dispositivos seg\u00fan el principio de captaci\u00f3n del dispositivo pueden ser: columna de agua oscilante, cuerpos flotantes, sistemas de rebosamiento, impacto, etc.<\/p>\n<p>3.- Energ\u00eda de las mareas o Maremotriz: basada en el aprovechamiento del ascenso y descenso del agua del mar (mareas) producido por la acci\u00f3n gravitatoria del Sol y la Luna. Una central maremotriz consiste en almacenar el agua en uno o varios embalses, se trata de construir un dique con unas compuertas que dan acceso a la entrada de agua o caudal a turbinar.<\/p>\n<p>4.- Energ\u00eda Maremot\u00e9rmica: se fundamenta en el aprovechamiento de la energ\u00eda t\u00e9rmica del mar basado en la diferencia de temperaturas entre la superficie del mar y las aguas profundas. Se requiere que haya un incremento t\u00e9rmico absoluto m\u00ednimo de 20\u00ba<\/p>\n<p>5.- Energ\u00eda del gradiente salino: es la energ\u00eda o por la diferencia en la concentraci\u00f3n de sal entre el agua de mar y la de los r\u00edos mediante un proceso de \u00f3smosis.<\/p>\n<p>Cedes distribuidor de Xenera.<\/p>\n<p>cedessl.es\u00a0 XENERA A CORU\u00d1A<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El aprovechamiento de mar para generar electricidad. Los Mares y oc\u00e9anos poseen un enorme potencial energ\u00e9tico que, a trav\u00e9s del uso de diferentes tecnolog\u00edas, pueden transformar en electricidad y ayuda a satisfacer las necesidades energ\u00e9ticas. Se pueden clasificar las Energ\u00edas del Mar, en funci\u00f3n de tecnolog\u00edas del tipo de aprovechamiento energ\u00e9tico. Y por ello tenemos&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/cedessl.org\/web1\/2019\/01\/16\/fuente-inagotable-de-energia-el-mar\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,4,8],"tags":[16,31,39,19,10,35,5],"class_list":["post-280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-vaquina-sale-barata","category-ahorro","category-promocion-xenera-empresa-electrica","tag-autoconsumo","tag-paga-menos-por-electricidad","tag-produccion-de-electricidad","tag-tarifa-electrica","tag-venta-electricidad","tag-xenera-compania-electrica","tag-xenera-coruna"],"_links":{"self":[{"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/posts\/280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/comments?post=280"}],"version-history":[{"count":1,"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/posts\/280\/revisions"}],"predecessor-version":[{"id":282,"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/posts\/280\/revisions\/282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/media\/281"}],"wp:attachment":[{"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/media?parent=280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/categories?post=280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/tags?post=280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}