{"id":206,"date":"2018-05-08T10:24:42","date_gmt":"2018-05-08T10:24:42","guid":{"rendered":"https:\/\/cedessl.org\/web1\/?p=206"},"modified":"2018-05-08T10:34:39","modified_gmt":"2018-05-08T10:34:39","slug":"mas-de-120-anos-de-historia","status":"publish","type":"post","link":"https:\/\/cedessl.org\/web1\/2018\/05\/08\/mas-de-120-anos-de-historia\/","title":{"rendered":"M\u00e1s de 120 a\u00f1os de historia"},"content":{"rendered":"<h4>CEDES- Distribuidor de XENERA en A Coru\u00f1a<\/h4>\n<p>La historia de XENERA COMPA\u00d1\u00cdA EL\u00c9CTRICA se remonta a hace 120 a\u00f1os cuando los abogados, Leoncio Comesa\u00f1a y Jos\u00e9 Leiras, tuvieron la intenci\u00f3n de abastecer a la ciudad de Tui de un importante servicio de electricidad que apenas exist\u00edan en Espa\u00f1a y, tan solo de manera excepcional en algunos puntos de Europa.<\/p>\n<p>Con el nombre de Compa\u00f1\u00eda El\u00e9ctrica de Tui construyeron una central hidroel\u00e9ctrica en Tebra, consiguiendo proveer de alumbrado el\u00e9ctrico a las casas de los personajes m\u00e1s influyentes de la ciudad en esa \u00e9poca.<\/p>\n<p>La Central el\u00e9ctrica, consigui\u00f3 en 1896 la autorizaci\u00f3n para atravesar el dominio comunal e instalar el tendido de cables que conducir\u00edan el fluido el\u00e9ctrico y telef\u00f3nico entre la central denominada \u201cMiudi\u00f1a\u201d y la ciudad de Tui, donde un poco m\u00e1s tarde tambi\u00e9n se implantar\u00eda el alumbrado p\u00fablico.<br \/>\nLa inauguraci\u00f3n del alumbrado p\u00fablico tuvo lugar el 16 de diciembre de 1896, donde se celebr\u00f3 en un acto solemne un gran banquete en el que los comensales alabaron a los fundadores de La Central el\u00e9ctrica por su iniciativa de car\u00e1cter innovador y visionario, dadas las grandes aplicaciones que la electricidad iba a tener.<\/p>\n<p>Actualmente XENERA es la mayor compa\u00f1\u00eda el\u00e9ctrica de capital gallego y dispone de centrales hidroel\u00e9ctricas, fotovoltaicas y e\u00f3licas a lo largo de toda Espa\u00f1a.<\/p>\n<p>Si deseas informaci\u00f3n comercial consulta condiciones en nuestra oficina de A Coru\u00f1a o en nuestra web www.cedessl.es<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CEDES- Distribuidor de XENERA en A Coru\u00f1a La historia de XENERA COMPA\u00d1\u00cdA EL\u00c9CTRICA se remonta a hace 120 a\u00f1os cuando los abogados, Leoncio Comesa\u00f1a y Jos\u00e9 Leiras, tuvieron la intenci\u00f3n de abastecer a la ciudad de Tui de un importante servicio de electricidad que apenas exist\u00edan en Espa\u00f1a y, tan solo de manera excepcional en&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/cedessl.org\/web1\/2018\/05\/08\/mas-de-120-anos-de-historia\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[13,5],"class_list":["post-206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia","tag-historia-de-xenera","tag-xenera-coruna"],"_links":{"self":[{"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/posts\/206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/comments?post=206"}],"version-history":[{"count":3,"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/posts\/206\/revisions"}],"predecessor-version":[{"id":210,"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/posts\/206\/revisions\/210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/media\/208"}],"wp:attachment":[{"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/media?parent=206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/categories?post=206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cedessl.org\/web1\/wp-json\/wp\/v2\/tags?post=206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}